{"id":189,"date":"2016-04-21T20:25:27","date_gmt":"2016-04-21T20:25:27","guid":{"rendered":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg"},"modified":"2016-04-21T20:30:26","modified_gmt":"2016-04-21T20:30:26","slug":"cimcvxp1-fix","status":"inherit","type":"attachment","link":"https:\/\/wilsontrailersales.net\/index.php\/sales\/cimcvxp1-fix\/","title":{"rendered":"cimcvxp"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-189","attachment","type-attachment","status-inherit","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>cimcvxp - Wilson Trailer Sales, Inc<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"cimcvxp - Wilson Trailer Sales, Inc\" \/>\n<meta property=\"og:description\" content=\"Continue reading\" \/>\n<meta property=\"og:url\" content=\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg\" \/>\n<meta property=\"og:site_name\" content=\"Wilson Trailer Sales, Inc\" \/>\n<meta property=\"article:modified_time\" content=\"2016-04-21T20:30:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1384\" \/>\n\t<meta property=\"og:image:height\" content=\"1787\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg\",\"url\":\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg\",\"name\":\"cimcvxp - Wilson Trailer Sales, Inc\",\"isPartOf\":{\"@id\":\"https:\/\/wilsontrailersales.net\/#website\"},\"datePublished\":\"2016-04-21T20:25:27+00:00\",\"dateModified\":\"2016-04-21T20:30:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/wilsontrailersales.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sales\",\"item\":\"https:\/\/wilsontrailersales.net\/index.php\/sales\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"cimcvxp\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/wilsontrailersales.net\/#website\",\"url\":\"https:\/\/wilsontrailersales.net\/\",\"name\":\"Wilson Trailer Sales\",\"description\":\"SERVICE AND SALES OF NEW AND USED SEMI TRAILERS\",\"publisher\":{\"@id\":\"https:\/\/wilsontrailersales.net\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/wilsontrailersales.net\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/wilsontrailersales.net\/#organization\",\"name\":\"Wilson Trailer Sales\",\"url\":\"https:\/\/wilsontrailersales.net\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/wilsontrailersales.net\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2015\/11\/logoclearsmall.png\",\"contentUrl\":\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2015\/11\/logoclearsmall.png\",\"width\":300,\"height\":38,\"caption\":\"Wilson Trailer Sales\"},\"image\":{\"@id\":\"https:\/\/wilsontrailersales.net\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"cimcvxp - Wilson Trailer Sales, Inc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg","og_locale":"en_US","og_type":"article","og_title":"cimcvxp - Wilson Trailer Sales, Inc","og_description":"Continue reading","og_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg","og_site_name":"Wilson Trailer Sales, Inc","article_modified_time":"2016-04-21T20:30:26+00:00","og_image":[{"width":1384,"height":1787,"url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg","url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg","name":"cimcvxp - Wilson Trailer Sales, Inc","isPartOf":{"@id":"https:\/\/wilsontrailersales.net\/#website"},"datePublished":"2016-04-21T20:25:27+00:00","dateModified":"2016-04-21T20:30:26+00:00","breadcrumb":{"@id":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/wilsontrailersales.net\/"},{"@type":"ListItem","position":2,"name":"Sales","item":"https:\/\/wilsontrailersales.net\/index.php\/sales\/"},{"@type":"ListItem","position":3,"name":"cimcvxp"}]},{"@type":"WebSite","@id":"https:\/\/wilsontrailersales.net\/#website","url":"https:\/\/wilsontrailersales.net\/","name":"Wilson Trailer Sales","description":"SERVICE AND SALES OF NEW AND USED SEMI TRAILERS","publisher":{"@id":"https:\/\/wilsontrailersales.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/wilsontrailersales.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/wilsontrailersales.net\/#organization","name":"Wilson Trailer Sales","url":"https:\/\/wilsontrailersales.net\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/wilsontrailersales.net\/#\/schema\/logo\/image\/","url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2015\/11\/logoclearsmall.png","contentUrl":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2015\/11\/logoclearsmall.png","width":300,"height":38,"caption":"Wilson Trailer Sales"},"image":{"@id":"https:\/\/wilsontrailersales.net\/#\/schema\/logo\/image\/"}}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"232\" height=\"300\" src=\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-232x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-232x300.jpg 232w, https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-768x992.jpg 768w, https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-793x1024.jpg 793w, https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-116x150.jpg 116w, https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg 1384w\" sizes=\"auto, (max-width: 232px) 100vw, 232px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p> <a class=\"continue-reading-link\" href=\"https:\/\/wilsontrailersales.net\/index.php\/sales\/cimcvxp1-fix\/\"><span>Continue reading<\/span><i class=\"crycon-right-dir\"><\/i><\/a> <\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1384,"height":1787,"file":"2016\/04\/cimcvxp1-fix.jpg","sizes":{"thumbnail":{"file":"cimcvxp1-fix-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-150x150.jpg"},"medium":{"file":"cimcvxp1-fix-232x300.jpg","width":232,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-232x300.jpg"},"medium_large":{"file":"cimcvxp1-fix-768x992.jpg","width":768,"height":992,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-768x992.jpg"},"large":{"file":"cimcvxp1-fix-793x1024.jpg","width":793,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-793x1024.jpg"},"custom":{"file":"cimcvxp1-fix-116x150.jpg","width":116,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-116x150.jpg"},"post-thumbnail":{"file":"cimcvxp1-fix-116x150.jpg","width":116,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-116x150.jpg"},"header":{"file":"cimcvxp1-fix-1200x150.jpg","width":1200,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-1200x150.jpg"},"slider":{"file":"cimcvxp1-fix-1384x580.jpg","width":1384,"height":580,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-1384x580.jpg"},"columns":{"file":"cimcvxp1-fix-400x311.jpg","width":400,"height":311,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix-400x311.jpg"},"full":{"file":"cimcvxp1-fix.jpg","width":1384,"height":1787,"mime_type":"image\/jpeg","source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":16,"source_url":"https:\/\/wilsontrailersales.net\/wp-content\/uploads\/2016\/04\/cimcvxp1-fix.jpg","_links":{"self":[{"href":"https:\/\/wilsontrailersales.net\/index.php\/wp-json\/wp\/v2\/media\/189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wilsontrailersales.net\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/wilsontrailersales.net\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/wilsontrailersales.net\/index.php\/wp-json\/wp\/v2\/users\/1"}]}}